{"id":2025,"date":"2013-04-04T18:15:22","date_gmt":"2013-04-04T18:15:22","guid":{"rendered":"http:\/\/granadablogs.com\/cableados\/?p=2025"},"modified":"2013-04-04T18:17:52","modified_gmt":"2013-04-04T18:17:52","slug":"la-politica-es-demasiado-importante-para-dejarla-solo-en-manos-de-los-politicos","status":"publish","type":"post","link":"https:\/\/granadablogs.com\/cableados\/2013\/04\/04\/la-politica-es-demasiado-importante-para-dejarla-solo-en-manos-de-los-politicos\/","title":{"rendered":"\u00abLa pol\u00edtica es demasiado importante para dejarla (solo) en manos de los pol\u00edticos\u00bb"},"content":{"rendered":"<p><a href=\"http:\/\/granadablogs.com\/cableados\/files\/2013\/04\/the-wall-pink-floyd-martillos.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/granadablogs.com\/cableados\/files\/2013\/04\/the-wall-pink-floyd-martillos-1024x575.jpg\" alt=\"the-wall-pink-floyd-martillos\" width=\"600\" height=\"375\" class=\"aligncenter size-large wp-image-2028\" \/><\/a><\/p>\n<p>Ma\u00f1ana de debate muy interesante sobre <strong>Gobierno Abierto<\/strong>. Distinguidos invitados, Streaming &amp; Twitter y creo que ha resultado ameno y con contenido.<\/p>\n<p>Escrib\u00ed previamente este post con <a href=\"http:\/\/granadablogs.com\/cableados\/2013\/04\/03\/gobierno-abierto-y-buques-de-guerra\/\" target=\"_blank\">las vicisitudes de Mr. John Pinkelton y su hijo<\/a>, sobre el que he basado mi intervenci\u00f3n. Al final, pienso que ha cambiado el modelo econ\u00f3mico, el ecosistema informativo y, tambi\u00e9n, est\u00e1 cambiando el pol\u00edtico. <strong>La Transici\u00f3n, ha terminado.<\/strong><\/p>\n<p>Ahora, a darnos cuenta y a trabajar para, salir la crisis, y cimentar nuestra democracia. Creo que es <strong>la clave del Gobierno Abierto, trabajo duro y solidez de las institucione<\/strong>s porque, como reza el titular de esta entrada: \u00abLa pol\u00edtica es demasiado importante para dejarla (solo) en manos de los pol\u00edticos\u00bb<\/p>\n<p><script type=\"text\/javascript\" src=\"\/\/storify.com\/juanlarzabal\/la-politica-es-demasiado-importante-para-dejarla.js\"><\/script><br \/>\n<noscript>[<a href=\"\/\/storify.com\/juanlarzabal\/la-politica-es-demasiado-importante-para-dejarla\" target=\"_blank\">View the story \u00ab\\\u00bbLa pol\u00edtica es demasiado importante para dejarla (solo) en manos de los pol\u00edticos\\\u00bb\u00bb on Storify<\/a>]<\/noscript><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ma\u00f1ana de debate muy interesante sobre Gobierno Abierto. Distinguidos invitados, Streaming &amp; Twitter y creo que ha resultado ameno y con contenido. Escrib\u00ed previamente este post con las vicisitudes de Mr. John Pinkelton y su hijo, sobre el que he basado mi intervenci\u00f3n. Al final, pienso que ha cambiado el modelo econ\u00f3mico, el ecosistema informativo [&hellip;]<\/p>\n","protected":false},"author":73,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18734,665],"tags":[],"class_list":["post-2025","post","type-post","status-publish","format-standard","hentry","category-2-0","category-politica"],"_links":{"self":[{"href":"https:\/\/granadablogs.com\/cableados\/wp-json\/wp\/v2\/posts\/2025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granadablogs.com\/cableados\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granadablogs.com\/cableados\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granadablogs.com\/cableados\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/granadablogs.com\/cableados\/wp-json\/wp\/v2\/comments?post=2025"}],"version-history":[{"count":3,"href":"https:\/\/granadablogs.com\/cableados\/wp-json\/wp\/v2\/posts\/2025\/revisions"}],"predecessor-version":[{"id":2027,"href":"https:\/\/granadablogs.com\/cableados\/wp-json\/wp\/v2\/posts\/2025\/revisions\/2027"}],"wp:attachment":[{"href":"https:\/\/granadablogs.com\/cableados\/wp-json\/wp\/v2\/media?parent=2025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granadablogs.com\/cableados\/wp-json\/wp\/v2\/categories?post=2025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granadablogs.com\/cableados\/wp-json\/wp\/v2\/tags?post=2025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}